{"id":173,"count":1,"description":"","link":"https:\/\/bcoceansideproperties.com\/blog\/tag\/homes-for-sale\/","name":"homes for sale","slug":"homes-for-sale","taxonomy":"post_tag","meta":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v24.5 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>homes for sale Archives - Our Latest Updates<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/bcoceansideproperties.com\/blog\/tag\/homes-for-sale\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"homes for sale Archives - Our Latest Updates\" \/>\n<meta property=\"og:url\" content=\"https:\/\/bcoceansideproperties.com\/blog\/tag\/homes-for-sale\/\" \/>\n<meta property=\"og:site_name\" content=\"Our Latest Updates\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"CollectionPage\",\"@id\":\"https:\/\/bcoceansideproperties.com\/blog\/tag\/homes-for-sale\/\",\"url\":\"https:\/\/bcoceansideproperties.com\/blog\/tag\/homes-for-sale\/\",\"name\":\"homes for sale Archives - Our Latest Updates\",\"isPartOf\":{\"@id\":\"https:\/\/bcoceansideproperties.com\/blog\/#website\"},\"breadcrumb\":{\"@id\":\"https:\/\/bcoceansideproperties.com\/blog\/tag\/homes-for-sale\/#breadcrumb\"},\"inLanguage\":\"en-CA\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/bcoceansideproperties.com\/blog\/tag\/homes-for-sale\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/bcoceansideproperties.com\/blog\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"homes for sale\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/bcoceansideproperties.com\/blog\/#website\",\"url\":\"https:\/\/bcoceansideproperties.com\/blog\/\",\"name\":\"Our Latest Updates\",\"description\":\"News, Market trends, and stats\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/bcoceansideproperties.com\/blog\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-CA\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"homes for sale Archives - Our Latest Updates","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/bcoceansideproperties.com\/blog\/tag\/homes-for-sale\/","og_locale":"en_US","og_type":"article","og_title":"homes for sale Archives - Our Latest Updates","og_url":"https:\/\/bcoceansideproperties.com\/blog\/tag\/homes-for-sale\/","og_site_name":"Our Latest Updates","twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"CollectionPage","@id":"https:\/\/bcoceansideproperties.com\/blog\/tag\/homes-for-sale\/","url":"https:\/\/bcoceansideproperties.com\/blog\/tag\/homes-for-sale\/","name":"homes for sale Archives - Our Latest Updates","isPartOf":{"@id":"https:\/\/bcoceansideproperties.com\/blog\/#website"},"breadcrumb":{"@id":"https:\/\/bcoceansideproperties.com\/blog\/tag\/homes-for-sale\/#breadcrumb"},"inLanguage":"en-CA"},{"@type":"BreadcrumbList","@id":"https:\/\/bcoceansideproperties.com\/blog\/tag\/homes-for-sale\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/bcoceansideproperties.com\/blog\/"},{"@type":"ListItem","position":2,"name":"homes for sale"}]},{"@type":"WebSite","@id":"https:\/\/bcoceansideproperties.com\/blog\/#website","url":"https:\/\/bcoceansideproperties.com\/blog\/","name":"Our Latest Updates","description":"News, Market trends, and stats","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/bcoceansideproperties.com\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-CA"}]}},"_links":{"self":[{"href":"https:\/\/bcoceansideproperties.com\/blog\/wp-json\/wp\/v2\/tags\/173"}],"collection":[{"href":"https:\/\/bcoceansideproperties.com\/blog\/wp-json\/wp\/v2\/tags"}],"about":[{"href":"https:\/\/bcoceansideproperties.com\/blog\/wp-json\/wp\/v2\/taxonomies\/post_tag"}],"wp:post_type":[{"href":"https:\/\/bcoceansideproperties.com\/blog\/wp-json\/wp\/v2\/posts?tags=173"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}